{"id":20156,"count":1,"description":"","link":"https:\/\/bongda.fuskered.com\/index.php\/tag\/como-indonesia-djarum-michael-bambang-hartono-robert-budi-hartono-serie-a-chuyen-nhuong\/","name":"Como Indonesia Djarum Michael Bambang Hartono Robert Budi Hartono Serie A chuy\u1ec3n nh\u01b0\u1ee3ng","slug":"como-indonesia-djarum-michael-bambang-hartono-robert-budi-hartono-serie-a-chuyen-nhuong","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bongda.fuskered.com\/index.php\/wp-json\/wp\/v2\/tags\/20156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bongda.fuskered.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bongda.fuskered.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bongda.fuskered.com\/index.php\/wp-json\/wp\/v2\/posts?tags=20156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}